{"id":225331,"date":"2024-07-26T18:25:00","date_gmt":"2024-07-26T22:25:00","guid":{"rendered":"https:\/\/athletesuntapped.com\/browse\/?page_id=225331"},"modified":"2024-10-15T09:59:06","modified_gmt":"2024-10-15T13:59:06","slug":"west-nashville-tn","status":"publish","type":"page","link":"https:\/\/athletesuntapped.com\/browse\/swimming\/tennessee\/west-nashville-tn\/","title":{"rendered":"West Nashville, TN"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"author":2,"featured_media":1497,"parent":59501,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"footnotes":""},"categories":[7],"tags":[22],"class_list":["post-225331","page","type-page","status-publish","has-post-thumbnail","hentry","category-city","tag-swimming"],"acf":[],"featured_image_src":"https:\/\/athletesuntapped.com\/browse\/wp-content\/uploads\/2024\/08\/Swimming-City-2.jpg","yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Swimming Lessons in West Nashville, TN | Vetted Coaches<\/title>\n<meta name=\"description\" content=\"Book swimming coaches in West Nashville, Tennessee. 1 pros for technique, stroke &amp; endurance. Lessons from $50. Untap your potential.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/athletesuntapped.com\/browse\/swimming\/tennessee\/west-nashville-tn\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Swimming Lessons in West Nashville, TN | Vetted Coaches\" \/>\n<meta property=\"og:description\" content=\"Book swimming coaches in West Nashville, Tennessee. 1 pros for technique, stroke &amp; endurance. Lessons from $50. Untap your potential.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/athletesuntapped.com\/browse\/swimming\/tennessee\/west-nashville-tn\/\" \/>\n<meta property=\"og:site_name\" content=\"Athletes Untapped | Find a Vetted Private Coach Near You\" \/>\n<meta property=\"article:modified_time\" content=\"2024-10-15T13:59:06+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/athletesuntapped.com\/browse\/wp-content\/uploads\/2024\/08\/Swimming-City-2.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2100\" \/>\n\t<meta property=\"og:image:height\" content=\"900\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/athletesuntapped.com\\\/browse\\\/swimming\\\/tennessee\\\/west-nashville-tn\\\/\",\"url\":\"https:\\\/\\\/athletesuntapped.com\\\/browse\\\/swimming\\\/tennessee\\\/west-nashville-tn\\\/\",\"name\":\"Swimming Lessons in West Nashville, TN | Vetted Coaches\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/athletesuntapped.com\\\/browse\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/athletesuntapped.com\\\/browse\\\/swimming\\\/tennessee\\\/west-nashville-tn\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/athletesuntapped.com\\\/browse\\\/swimming\\\/tennessee\\\/west-nashville-tn\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/athletesuntapped.com\\\/browse\\\/wp-content\\\/uploads\\\/2024\\\/08\\\/Swimming-City-2.jpg\",\"datePublished\":\"2024-07-26T22:25:00+00:00\",\"dateModified\":\"2024-10-15T13:59:06+00:00\",\"description\":\"Book swimming coaches in West Nashville, Tennessee. 1 pros for technique, stroke & endurance. Lessons from $50. Untap your potential.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/athletesuntapped.com\\\/browse\\\/swimming\\\/tennessee\\\/west-nashville-tn\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/athletesuntapped.com\\\/browse\\\/swimming\\\/tennessee\\\/west-nashville-tn\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/athletesuntapped.com\\\/browse\\\/swimming\\\/tennessee\\\/west-nashville-tn\\\/#primaryimage\",\"url\":\"https:\\\/\\\/athletesuntapped.com\\\/browse\\\/wp-content\\\/uploads\\\/2024\\\/08\\\/Swimming-City-2.jpg\",\"contentUrl\":\"https:\\\/\\\/athletesuntapped.com\\\/browse\\\/wp-content\\\/uploads\\\/2024\\\/08\\\/Swimming-City-2.jpg\",\"width\":2100,\"height\":900,\"caption\":\"Train with an Athletes Untapped Private Swimming Coach and UNTAP your potential!\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/athletesuntapped.com\\\/browse\\\/#website\",\"url\":\"https:\\\/\\\/athletesuntapped.com\\\/browse\\\/\",\"name\":\"Athletes Untapped | Book Lessons with a Private Sports Coach\",\"description\":\"Book individual, group, or team training lessons with a vetted private sports coach!\",\"publisher\":{\"@id\":\"https:\\\/\\\/athletesuntapped.com\\\/browse\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/athletesuntapped.com\\\/browse\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/athletesuntapped.com\\\/browse\\\/#organization\",\"name\":\"Athletes Untapped\",\"url\":\"https:\\\/\\\/athletesuntapped.com\\\/browse\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/athletesuntapped.com\\\/browse\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/athletesuntapped.com\\\/browse\\\/wp-content\\\/uploads\\\/2024\\\/07\\\/cropped-AU-1.png\",\"contentUrl\":\"https:\\\/\\\/athletesuntapped.com\\\/browse\\\/wp-content\\\/uploads\\\/2024\\\/07\\\/cropped-AU-1.png\",\"width\":512,\"height\":512,\"caption\":\"Athletes Untapped\"},\"image\":{\"@id\":\"https:\\\/\\\/athletesuntapped.com\\\/browse\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Swimming Lessons in West Nashville, TN | Vetted Coaches","description":"Book swimming coaches in West Nashville, Tennessee. 1 pros for technique, stroke & endurance. Lessons from $50. Untap your potential.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/athletesuntapped.com\/browse\/swimming\/tennessee\/west-nashville-tn\/","og_locale":"en_US","og_type":"article","og_title":"Swimming Lessons in West Nashville, TN | Vetted Coaches","og_description":"Book swimming coaches in West Nashville, Tennessee. 1 pros for technique, stroke & endurance. Lessons from $50. Untap your potential.","og_url":"https:\/\/athletesuntapped.com\/browse\/swimming\/tennessee\/west-nashville-tn\/","og_site_name":"Athletes Untapped | Find a Vetted Private Coach Near You","article_modified_time":"2024-10-15T13:59:06+00:00","og_image":[{"width":2100,"height":900,"url":"https:\/\/athletesuntapped.com\/browse\/wp-content\/uploads\/2024\/08\/Swimming-City-2.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/athletesuntapped.com\/browse\/swimming\/tennessee\/west-nashville-tn\/","url":"https:\/\/athletesuntapped.com\/browse\/swimming\/tennessee\/west-nashville-tn\/","name":"Swimming Lessons in West Nashville, TN | Vetted Coaches","isPartOf":{"@id":"https:\/\/athletesuntapped.com\/browse\/#website"},"primaryImageOfPage":{"@id":"https:\/\/athletesuntapped.com\/browse\/swimming\/tennessee\/west-nashville-tn\/#primaryimage"},"image":{"@id":"https:\/\/athletesuntapped.com\/browse\/swimming\/tennessee\/west-nashville-tn\/#primaryimage"},"thumbnailUrl":"https:\/\/athletesuntapped.com\/browse\/wp-content\/uploads\/2024\/08\/Swimming-City-2.jpg","datePublished":"2024-07-26T22:25:00+00:00","dateModified":"2024-10-15T13:59:06+00:00","description":"Book swimming coaches in West Nashville, Tennessee. 1 pros for technique, stroke & endurance. Lessons from $50. Untap your potential.","breadcrumb":{"@id":"https:\/\/athletesuntapped.com\/browse\/swimming\/tennessee\/west-nashville-tn\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/athletesuntapped.com\/browse\/swimming\/tennessee\/west-nashville-tn\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/athletesuntapped.com\/browse\/swimming\/tennessee\/west-nashville-tn\/#primaryimage","url":"https:\/\/athletesuntapped.com\/browse\/wp-content\/uploads\/2024\/08\/Swimming-City-2.jpg","contentUrl":"https:\/\/athletesuntapped.com\/browse\/wp-content\/uploads\/2024\/08\/Swimming-City-2.jpg","width":2100,"height":900,"caption":"Train with an Athletes Untapped Private Swimming Coach and UNTAP your potential!"},{"@type":"WebSite","@id":"https:\/\/athletesuntapped.com\/browse\/#website","url":"https:\/\/athletesuntapped.com\/browse\/","name":"Athletes Untapped | Book Lessons with a Private Sports Coach","description":"Book individual, group, or team training lessons with a vetted private sports coach!","publisher":{"@id":"https:\/\/athletesuntapped.com\/browse\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/athletesuntapped.com\/browse\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/athletesuntapped.com\/browse\/#organization","name":"Athletes Untapped","url":"https:\/\/athletesuntapped.com\/browse\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/athletesuntapped.com\/browse\/#\/schema\/logo\/image\/","url":"https:\/\/athletesuntapped.com\/browse\/wp-content\/uploads\/2024\/07\/cropped-AU-1.png","contentUrl":"https:\/\/athletesuntapped.com\/browse\/wp-content\/uploads\/2024\/07\/cropped-AU-1.png","width":512,"height":512,"caption":"Athletes Untapped"},"image":{"@id":"https:\/\/athletesuntapped.com\/browse\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/athletesuntapped.com\/browse\/wp-json\/wp\/v2\/pages\/225331","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/athletesuntapped.com\/browse\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/athletesuntapped.com\/browse\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/athletesuntapped.com\/browse\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/athletesuntapped.com\/browse\/wp-json\/wp\/v2\/comments?post=225331"}],"version-history":[{"count":0,"href":"https:\/\/athletesuntapped.com\/browse\/wp-json\/wp\/v2\/pages\/225331\/revisions"}],"up":[{"embeddable":true,"href":"https:\/\/athletesuntapped.com\/browse\/wp-json\/wp\/v2\/pages\/59501"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/athletesuntapped.com\/browse\/wp-json\/wp\/v2\/media\/1497"}],"wp:attachment":[{"href":"https:\/\/athletesuntapped.com\/browse\/wp-json\/wp\/v2\/media?parent=225331"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/athletesuntapped.com\/browse\/wp-json\/wp\/v2\/categories?post=225331"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/athletesuntapped.com\/browse\/wp-json\/wp\/v2\/tags?post=225331"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}